{"id":3899,"date":"2016-09-30T17:37:38","date_gmt":"2016-09-30T15:37:38","guid":{"rendered":"https:\/\/www.stempeltier.de\/blog\/?p=3899"},"modified":"2016-09-30T17:48:51","modified_gmt":"2016-09-30T15:48:51","slug":"nachwuchs-im-team-stempeltier","status":"publish","type":"post","link":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/","title":{"rendered":"Nachwuchs im Team Stempeltier"},"content":{"rendered":"<p style=\"text-align: left;\"><strong>Was ich am liebsten bastele?<\/strong><\/p>\n<p style=\"text-align: left;\">Ganz eindeutig s\u00fc\u00dfe Kleinigkeiten, die nach dem Enstehen dann auf Reise gehen d\u00fcrfen, um einen lieben Menschen zu \u00fcberraschen und erfreuen \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3901 alignleft\" src=\"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/01\/charmaine-team-stempeltier-einsteigen.jpg\" alt=\"charmaine-team-stempeltier-einsteigen\" width=\"159\" height=\"200\" \/>Letzte Woche hat wieder eine meiner Kundinnen den Schritt gewagt und ist selbst <strong>Demonstratorin<\/strong> geworden. Die Motivation war sicherlich mitunter die Ersparnis von mind. 20% die sie nun auf alle Ihre Eink\u00e4ufe bei Stampin&#8216; Up! haben wird. Da freut sich das Bastlerherz.<\/p>\n<p>Herzlichen Gl\u00fcckwunsch! Du wirst es nicht bereuen &#8211; ich sprech&#8216; da aus Erfahrung. Bin ja schliesslich auch erst ein gutes Jahr dabei und genie\u00dfe es immer mehr und mehr.<\/p>\n<p>Ich freue mich sehr, die liebe Charmaine aus Lippstadt als neuestes Stempeltierchen im <a href=\"https:\/\/www.stempeltier.de\/blog\/stampin_up_demo-werden-einsteigen-starterset\/team-stempeltier\/\"><span style=\"color: #ff9900;\"><strong>Team<\/strong> <\/span><\/a>begr\u00fc\u00dfen zu d\u00fcrfen.<\/p>\n<p>Wenn ihr aus dem Kreis <strong>LIPPSTADT<\/strong> kommt, und noch keine Demonstratorin Eures Vertrauens habt, dann meldet euch bei <a href=\"m&#97;&#105;&#x6c;&#x74;&#x6f;:c&#104;&#97;&#x72;&#x6d;&#x61;i&#110;&#101;&#46;&#x73;&#x63;&#x68;e&#108;&#108;&#x40;&#x79;&#x61;ho&#111;&#46;&#x64;&#x65;\">Charmaine<\/a>. Sie freut sich \u00fcber neue Kontakte.<\/p>\n<p>Nat\u00fcrlich habe ich mich gleich an meinen Basteltisch gesetzt, um ihr ein Willkommensgeschenk fertig zu machen und die Tage auf die Reise zu schicken.<\/p>\n<p>Was es ist, wird noch nicht verraten &#8211; soll ja eine <span style=\"color: #ff6600;\"><strong>\u00dcberraschung<\/strong> <\/span>sein \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3904\" src=\"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/09\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg\" alt=\"willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen\" width=\"667\" height=\"435\" srcset=\"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/09\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg 667w, https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/09\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen-600x391.jpg 600w, https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/09\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen-300x196.jpg 300w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Nat\u00fcrlich wird sich damit mein <strong>Teamgeschenk<\/strong> mit Farbring \u2013 inklusive eines speziell f\u00fcr Charmaine ausgew\u00e4hlten Geschenks auf den Weg zu ihr machen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1519\" src=\"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/06\/stempeltier-stampin-up-team-einsteigen-demo-werden-demonstratorin-Einstieg-Begr\u00fc\u00dfungspaket-geschenk-farbf\u00e4cher-1.jpg\" alt=\"stempeltier stampin up team einsteigen demo werden demonstratorin Einstieg Begr\u00fc\u00dfungspaket geschenk farbf\u00e4cher 1\" width=\"1000\" height=\"687\" srcset=\"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/06\/stempeltier-stampin-up-team-einsteigen-demo-werden-demonstratorin-Einstieg-Begr\u00fc\u00dfungspaket-geschenk-farbf\u00e4cher-1.jpg 1000w, https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/06\/stempeltier-stampin-up-team-einsteigen-demo-werden-demonstratorin-Einstieg-Begr\u00fc\u00dfungspaket-geschenk-farbf\u00e4cher-1-600x412.jpg 600w, https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/06\/stempeltier-stampin-up-team-einsteigen-demo-werden-demonstratorin-Einstieg-Begr\u00fc\u00dfungspaket-geschenk-farbf\u00e4cher-1-300x206.jpg 300w, https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/06\/stempeltier-stampin-up-team-einsteigen-demo-werden-demonstratorin-Einstieg-Begr\u00fc\u00dfungspaket-geschenk-farbf\u00e4cher-1-768x528.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Du m\u00f6chtest gerne selbst auch so nette Post bekommen?<br \/>\nUnd nebenbei noch dauerhaft sparen auf alle Stampin&#8216; Up! Eink\u00e4ufe?<br \/>\nDu \u00fcberlegst vielleicht schon eine Weile, selbst<a href=\"https:\/\/www.stempeltier.de\/blog\/stampin_up_demo-werden-einsteigen-starterset\/\"><span style=\"color: #808080;\"> <strong>als Demo bei Stampin&#8216; Up! einzusteigen<\/strong> <\/span><\/a>und noch Fragen hast, dann melde dich doch einfach ganz unverbindlich. Ich beantworte gerne alle Fragenund freue mich \u00fcber weiteren <strong>Nachwuchs in meinem Team.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Wenn du die Karte nachwerkeln willst, findest du hier die verwendeten Stampin&#8216; Up! Materialien:<\/p>\n<div class=\"stampused stampused-wrap\">\n  <div class=\"stampused-item stampused-item-small\">\n    <a href=\"https:\/\/www.stampinup.de\/products\/141123?demoid=5017664\" \n                alt=\"Stampin Up Product 141123\" title=\"Stampin Up Online Shop Product 141123\" target=\"_blank\">\n                <img decoding=\"async\" src=\"\/\/www2.stampinup.com\/images\/EC\/141123s.jpg\" alt=\"Stampin Up Product 141123\"><\/a>  <\/div>\n  <div class=\"stampused-item stampused-item-small\">\n    <a href=\"https:\/\/www.stampinup.de\/products\/130517?demoid=5017664\" \n                alt=\"Stampin Up Product 130517\" title=\"Stampin Up Online Shop Product 130517\" target=\"_blank\">\n                <img decoding=\"async\" src=\"\/\/www2.stampinup.com\/images\/EC\/130517s.jpg\" alt=\"Stampin Up Product 130517\"><\/a>  <\/div>\n  <div class=\"stampused-item stampused-item-small\">\n    <a href=\"https:\/\/www.stampinup.de\/products\/131291?demoid=5017664\" \n                alt=\"Stampin Up Product 131291\" title=\"Stampin Up Online Shop Product 131291\" target=\"_blank\">\n                <img decoding=\"async\" src=\"\/\/www2.stampinup.com\/images\/EC\/131291s.jpg\" alt=\"Stampin Up Product 131291\"><\/a>  <\/div>\n  <div class=\"stampused-item stampused-item-small\">\n    <a href=\"https:\/\/www.stampinup.de\/products\/108611?demoid=5017664\" \n                alt=\"Stampin Up Product 108611\" title=\"Stampin Up Online Shop Product 108611\" target=\"_blank\">\n                <img decoding=\"async\" src=\"\/\/www2.stampinup.com\/images\/EC\/108611s.jpg\" alt=\"Stampin Up Product 108611\"><\/a>  <\/div>\n  <div class=\"stampused-item stampused-item-small\">\n    <a href=\"https:\/\/www.stampinup.de\/products\/106549?demoid=5017664\" \n                alt=\"Stampin Up Product 106549\" title=\"Stampin Up Online Shop Product 106549\" target=\"_blank\">\n                <img decoding=\"async\" src=\"\/\/www2.stampinup.com\/images\/EC\/106549s.jpg\" alt=\"Stampin Up Product 106549\"><\/a>  <\/div>\n  <div class=\"stampused-item stampused-item-small\">\n    <a href=\"https:\/\/www.stampinup.de\/products\/131179?demoid=5017664\" \n                alt=\"Stampin Up Product 131179\" title=\"Stampin Up Online Shop Product 131179\" target=\"_blank\">\n                <img decoding=\"async\" src=\"\/\/www2.stampinup.com\/images\/EC\/131179s.jpg\" alt=\"Stampin Up Product 131179\"><\/a>  <\/div>\n  <div class=\"stampused-item stampused-item-small\">\n    <a href=\"https:\/\/www.stampinup.de\/products\/126957?demoid=5017664\" \n                alt=\"Stampin Up Product 126957\" title=\"Stampin Up Online Shop Product 126957\" target=\"_blank\">\n                <img decoding=\"async\" src=\"\/\/www2.stampinup.com\/images\/EC\/126957s.jpg\" alt=\"Stampin Up Product 126957\"><\/a>  <\/div>\n  <div class=\"stampused-item stampused-item-small\">\n    <a href=\"https:\/\/www.stampinup.de\/products\/119246?demoid=5017664\" \n                alt=\"Stampin Up Product 119246\" title=\"Stampin Up Online Shop Product 119246\" target=\"_blank\">\n                <img decoding=\"async\" src=\"\/\/www2.stampinup.com\/images\/EC\/119246s.jpg\" alt=\"Stampin Up Product 119246\"><\/a>  <\/div>\n  <div class=\"stampused-item stampused-item-small\">\n    <a href=\"https:\/\/www.stampinup.de\/products\/110755?demoid=5017664\" \n                alt=\"Stampin Up Product 110755\" title=\"Stampin Up Online Shop Product 110755\" target=\"_blank\">\n                <img decoding=\"async\" src=\"\/\/www2.stampinup.com\/images\/EC\/110755s.jpg\" alt=\"Stampin Up Product 110755\"><\/a>  <\/div>\n  <div class=\"stampused-item stampused-item-small\">\n    <a href=\"https:\/\/www.stampinup.de\/products\/104430?demoid=5017664\" \n                alt=\"Stampin Up Product 104430\" title=\"Stampin Up Online Shop Product 104430\" target=\"_blank\">\n                <img decoding=\"async\" src=\"\/\/www2.stampinup.com\/images\/EC\/104430s.jpg\" alt=\"Stampin Up Product 104430\"><\/a>  <\/div>\n<\/div>\n\n<p>&nbsp;<\/p>\n<h3>Du m\u00f6chtest mehr \u00fcber Stampin&#8216; Up! wissen?<\/h3>\n<p>Dann melde dich bei mir und vereinbare einen Termin zur <a href=\"https:\/\/www.stempeltier.de\/blog\/gastgeberin\/\"><strong>Stempelparty<\/strong><\/a>. F\u00fcr dich als <strong><span style=\"color: #ff6600;\">Gastgeberin<\/span> <\/strong>gibt es tolle Shoppingvorteile. Ausserdem darfst du dir bei einem Partyumsatz ab 200 EUR die <strong>exklusiven<\/strong> <strong>Gastgeberinnenpr\u00e4mien<\/strong> kaufen.<br \/>\nRuf mich einfach an, oder schreib mir eine <a href=\"https:\/\/www.stempeltier.de\/blog\/ein-botanischer-garten-im-domecup\/\">Email<\/a>, falls du Lust auf einen Bastelnachmittag \/ Bastelabend bei dir zu Hause hast. Das Thema stimmen wir beiden dann miteinander ab, ich gehe auf deine W\u00fcnsche ein. Ich freu mich auf Dich.<\/p>\n<p>&nbsp;<\/p>\n<p>LG, Danny<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.stempeltier.de\/blog\/stampin_up_treuepunkte_stempeltier\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1129 size-medium\" src=\"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/10\/logo-stempeltier-treuepunkte-021-300x100.png\" alt=\"logo stempeltier treuepunkte 02\" width=\"300\" height=\"100\" srcset=\"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/10\/logo-stempeltier-treuepunkte-021-300x100.png 300w, https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/10\/logo-stempeltier-treuepunkte-021.png 590w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Mit deinen Bestellungen bei mir sammelst du <a href=\"https:\/\/www.stempeltier.de\/blog\/stampin_up_treuepunkte_stempeltier\/\"><strong>Treuepunkte<\/strong><\/a>, die du gegen einen Wertgutschein einl\u00f6sen kannst. Weitere infos<a href=\"https:\/\/www.stempeltier.de\/blog\/stampin_up_treuepunkte_stempeltier\/\"> KLICKE HIER.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.stempeltier.de\/blog\/stampin_up_demo-werden\/\" rel=\"attachment wp-att-1523\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1523 size-medium\" src=\"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/06\/stempeltier-stampin-up-team-einsteigen-demo-werden-demonstratorin-Einstieg-Begr%C3%BC%C3%9Fungspaket-sale-a-bration-300x31.jpg\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/06\/stempeltier-stampin-up-team-einsteigen-demo-werden-demonstratorin-Einstieg-Begr\u00fc\u00dfungspaket-sale-a-bration-300x31.jpg 300w, https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/06\/stempeltier-stampin-up-team-einsteigen-demo-werden-demonstratorin-Einstieg-Begr\u00fc\u00dfungspaket-sale-a-bration-768x78.jpg 768w, https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2015\/06\/stempeltier-stampin-up-team-einsteigen-demo-werden-demonstratorin-Einstieg-Begr\u00fc\u00dfungspaket-sale-a-bration.jpg 1000w\" alt=\"stempeltier stampin up team einsteigen demo werden demonstratorin Einstieg Begr\u00fc\u00dfungspaket sale a bration\" width=\"300\" height=\"31\" \/><\/a><\/p>\n<p>Du m\u00f6chtest gerne dauerhaft mindestens <strong>20%<\/strong> auf deine Produkte bei Stampin\u2018 Up! <strong>sparen<\/strong>?<br \/>\nHast Lust neue Leute kennen zu lernen und auf einen Nebenjob mit freier Zeiteinteilung?<br \/>\nDann komm ins Team Stempeltier und sichere dir als Demo exklusive Vorteile.<br \/>\nMelde dich einfach, dann sprechen wir alles durch. <a href=\"https:\/\/www.stempeltier.de\/blog\/stampin_up_demo-werden\/\">Weitere Infos hier<\/a>. Den <a href=\"https:\/\/ida.stampinup.com\">Onlinevertrag <\/a>kannst du <a href=\"https:\/\/ida.stampinup.com\">hier <\/a>einsehen. Ich freu mich auf Dich!<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\">Frei nach dem Leitspruch von Stampin&#8216; Up!:<\/p>\n<blockquote>\n<p style=\"text-align: center;\"><strong>Wir <span style=\"color: #ff6600;\">lieben<\/span> was wir tun,<\/strong><br \/>\n<strong>zu <span style=\"color: #008080;\">teilen<\/span> was wir lieben und somit anderen zu helfen<\/strong><br \/>\n<strong>durch <span style=\"color: #808000;\">eigene Kreativit\u00e4t<\/span> Erfolge zu erzielen&#8230;.<\/strong><br \/>\n<strong>Dadurch zeichnen wir uns aus.<\/strong><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<div class=\"shariff shariff-align-center shariff-widget-align-left\" data-services=\"facebook%7Cpinterest\" data-url=\"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/\" data-timestamp=\"1475257731\" data-backendurl=\"https:\/\/www.stempeltier.de\/blog\/wp-json\/shariff\/v1\/share_counts?\"><div class=\"ShariffHeadline\">Sharing is caring - Teilen erlaubt<\/div><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.stempeltier.de%2Fblog%2Fnachwuchs-im-team-stempeltier%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span data-service=\"facebook\" style=\"color:#3b5998\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.stempeltier.de%2Fblog%2Fnachwuchs-im-team-stempeltier%2F&text=Nachwuchs%20im%20Team%20Stempeltier\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fwww.stempeltier.de%2Fblog%2Fnachwuchs-im-team-stempeltier%2F&media=https%3A%2F%2Fwww.stempeltier.de%2Fblog%2Fwp-content%2Fuploads%2F2016%2F09%2Fwillkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg&description=Nachwuchs%20im%20Team%20Stempeltier\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><span data-service=\"pinterest\" style=\"color:#cb2027\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.stempeltier.de%2Fblog%2Fnachwuchs-im-team-stempeltier%2F%20Nachwuchs%20im%20Team%20Stempeltier\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button mailto shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"mailto:?body=https%3A%2F%2Fwww.stempeltier.de%2Fblog%2Fnachwuchs-im-team-stempeltier%2F&subject=Nachwuchs%20im%20Team%20Stempeltier\" title=\"Per E-Mail versenden\" aria-label=\"Per E-Mail versenden\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#999\" d=\"M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Was ich am liebsten bastele? Ganz eindeutig s\u00fc\u00dfe Kleinigkeiten, die nach dem Enstehen dann auf Reise gehen d\u00fcrfen, um einen lieben Menschen zu \u00fcberraschen und erfreuen \ud83d\ude42 Letzte Woche hat wieder eine meiner Kundinnen den Schritt gewagt und ist selbst&hellip; <\/p>\n","protected":false},"author":1,"featured_media":3904,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[13,12],"tags":[226,328],"class_list":["post-3899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grusskarten","category-mitbringsel-geschenke","tag-demo-werden","tag-team-stempeltier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachwuchs im Team Stempeltier - Stempeltier<\/title>\n<meta name=\"description\" content=\"Kreativ mit Stempeln, Stanzen und Papier mit dem Stempeltier Danny und Stampin&#039; Up!\u00ae\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachwuchs im Team Stempeltier - Stempeltier\" \/>\n<meta property=\"og:description\" content=\"Kreativ mit Stempeln, Stanzen und Papier mit dem Stempeltier Danny und Stampin&#039; Up!\u00ae\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/\" \/>\n<meta property=\"og:site_name\" content=\"Stempeltier\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/DasStempeltier\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/DasStempeltier\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-30T15:37:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-30T15:48:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/09\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"667\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/\"},\"author\":{\"name\":\"Danny\",\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/#\\\/schema\\\/person\\\/9098e52c1c401acca4f656a62559c76e\"},\"headline\":\"Nachwuchs im Team Stempeltier\",\"datePublished\":\"2016-09-30T15:37:38+00:00\",\"dateModified\":\"2016-09-30T15:48:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/\"},\"wordCount\":494,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg\",\"keywords\":[\"demo werden\",\"Team Stempeltier\"],\"articleSection\":[\"Gru\u00dfkarten\",\"Mitbringsel &amp; Geschenke\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/\",\"url\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/\",\"name\":\"Nachwuchs im Team Stempeltier - Stempeltier\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg\",\"datePublished\":\"2016-09-30T15:37:38+00:00\",\"dateModified\":\"2016-09-30T15:48:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/#\\\/schema\\\/person\\\/9098e52c1c401acca4f656a62559c76e\"},\"description\":\"Kreativ mit Stempeln, Stanzen und Papier mit dem Stempeltier Danny und Stampin' Up!\u00ae\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg\",\"width\":667,\"height\":435,\"caption\":\"willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/nachwuchs-im-team-stempeltier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachwuchs im Team Stempeltier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/\",\"name\":\"Stempeltier\",\"description\":\"Kreative Gl\u00fccksmomente aus Papier\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.stempeltier.de\\\/blog\\\/#\\\/schema\\\/person\\\/9098e52c1c401acca4f656a62559c76e\",\"name\":\"Danny\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0830cd392492f28013917bb56ea915645f6517902d1355697338cbb7cdacc4ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0830cd392492f28013917bb56ea915645f6517902d1355697338cbb7cdacc4ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0830cd392492f28013917bb56ea915645f6517902d1355697338cbb7cdacc4ba?s=96&d=mm&r=g\",\"caption\":\"Danny\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DasStempeltier\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachwuchs im Team Stempeltier - Stempeltier","description":"Kreativ mit Stempeln, Stanzen und Papier mit dem Stempeltier Danny und Stampin' Up!\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/","og_locale":"de_DE","og_type":"article","og_title":"Nachwuchs im Team Stempeltier - Stempeltier","og_description":"Kreativ mit Stempeln, Stanzen und Papier mit dem Stempeltier Danny und Stampin' Up!\u00ae","og_url":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/","og_site_name":"Stempeltier","article_publisher":"http:\/\/www.facebook.com\/DasStempeltier","article_author":"https:\/\/www.facebook.com\/DasStempeltier\/","article_published_time":"2016-09-30T15:37:38+00:00","article_modified_time":"2016-09-30T15:48:51+00:00","og_image":[{"width":667,"height":435,"url":"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/09\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg","type":"image\/jpeg"}],"author":"Danny","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Danny","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/#article","isPartOf":{"@id":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/"},"author":{"name":"Danny","@id":"https:\/\/www.stempeltier.de\/blog\/#\/schema\/person\/9098e52c1c401acca4f656a62559c76e"},"headline":"Nachwuchs im Team Stempeltier","datePublished":"2016-09-30T15:37:38+00:00","dateModified":"2016-09-30T15:48:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/"},"wordCount":494,"commentCount":1,"image":{"@id":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/09\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg","keywords":["demo werden","Team Stempeltier"],"articleSection":["Gru\u00dfkarten","Mitbringsel &amp; Geschenke"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/","url":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/","name":"Nachwuchs im Team Stempeltier - Stempeltier","isPartOf":{"@id":"https:\/\/www.stempeltier.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/#primaryimage"},"image":{"@id":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/09\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg","datePublished":"2016-09-30T15:37:38+00:00","dateModified":"2016-09-30T15:48:51+00:00","author":{"@id":"https:\/\/www.stempeltier.de\/blog\/#\/schema\/person\/9098e52c1c401acca4f656a62559c76e"},"description":"Kreativ mit Stempeln, Stanzen und Papier mit dem Stempeltier Danny und Stampin' Up!\u00ae","breadcrumb":{"@id":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/#primaryimage","url":"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/09\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg","contentUrl":"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/09\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg","width":667,"height":435,"caption":"willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-im-team-stempeltier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.stempeltier.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Nachwuchs im Team Stempeltier"}]},{"@type":"WebSite","@id":"https:\/\/www.stempeltier.de\/blog\/#website","url":"https:\/\/www.stempeltier.de\/blog\/","name":"Stempeltier","description":"Kreative Gl\u00fccksmomente aus Papier","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stempeltier.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.stempeltier.de\/blog\/#\/schema\/person\/9098e52c1c401acca4f656a62559c76e","name":"Danny","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0830cd392492f28013917bb56ea915645f6517902d1355697338cbb7cdacc4ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0830cd392492f28013917bb56ea915645f6517902d1355697338cbb7cdacc4ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0830cd392492f28013917bb56ea915645f6517902d1355697338cbb7cdacc4ba?s=96&d=mm&r=g","caption":"Danny"},"sameAs":["https:\/\/www.facebook.com\/DasStempeltier\/"]}]}},"jetpack_featured_media_url":"https:\/\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/09\/willkommen-demo-werden-einsteigen-blog-stampin-up-stempeltier-demonstrator-werden-sparen.jpg","jetpack-related-posts":[{"id":2098,"url":"https:\/\/www.stempeltier.de\/blog\/herzlich-willkommen-einsteigen\/","url_meta":{"origin":3899,"position":0},"title":"Herzlich willkommen im Team Stempeltier","author":"Danny","date":"30. Januar 2016","format":false,"excerpt":"... wieder ist eine Karte f\u00fcr ein neues Mitglied in der Stempeltier-Familie auf die Reise gegangen. Ich freue mich sehr, die liebe Evi in meinem Team begr\u00fc\u00dfen zu d\u00fcrfen. Wenn du schon \u00fcberlegst, selbst als Demo bei Stampin' Up! einzusteigen und noch Fragen hast, dann melde dich doch einfach ganz\u2026","rel":"","context":"In &quot;Fr\u00fchjahr-Sommerkatalog 2016&quot;","block_context":{"text":"Fr\u00fchjahr-Sommerkatalog 2016","link":"https:\/\/www.stempeltier.de\/blog\/category\/fruehjahr-sommerkatalog-2016\/"},"img":{"alt_text":"herzlich willkommen stampin up stempeltier demo werden einsteigen","src":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/01\/herzlich-willkommen-stampin-up-stempeltier-demo-werden-einsteigen.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/01\/herzlich-willkommen-stampin-up-stempeltier-demo-werden-einsteigen.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/01\/herzlich-willkommen-stampin-up-stempeltier-demo-werden-einsteigen.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/01\/herzlich-willkommen-stampin-up-stempeltier-demo-werden-einsteigen.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2474,"url":"https:\/\/www.stempeltier.de\/blog\/geschenke-von-meinen-teammaedels\/","url_meta":{"origin":3899,"position":1},"title":"Geschenke von meinen Teamm\u00e4dels","author":"Danny","date":"25. M\u00e4rz 2016","format":false,"excerpt":"Ich muss euch heute einfach mal sagen, wie stolz ich auf meine Stempeltier M\u00e4dels bin. Die sind alles so kreativ und lieb, dass sie sich einen dicken Dr\u00fccker und ein herzliches Dankesch\u00f6n verdient haben. In den letzten Tagen hat der Postbote mich gleich 2 mal mit Geschenken meiner Teammitglieder \u00fcberrascht,\u2026","rel":"","context":"In &quot;Allgemein&quot;","block_context":{"text":"Allgemein","link":"https:\/\/www.stempeltier.de\/blog\/category\/allgemein\/"},"img":{"alt_text":"post team stempeltier geschenke stampin up ostern 600","src":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/03\/post-team-stempeltier-geschenke-stampin-up-ostern-600.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/03\/post-team-stempeltier-geschenke-stampin-up-ostern-600.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/03\/post-team-stempeltier-geschenke-stampin-up-ostern-600.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":10693,"url":"https:\/\/www.stempeltier.de\/blog\/willkommen-im-team-stempeltier-2\/","url_meta":{"origin":3899,"position":2},"title":"Willkommen im Team Stempeltier","author":"Danny","date":"15. April 2020","format":false,"excerpt":"Es war einiges los in den letzten Wochen und es gab wieder neue M\u00e4dels im Team Stempeltier zu begr\u00fc\u00dfen. Die Willkommenspost ist mittlerweile angekommen, so dass ich euch noch kurz ein paar Eindr\u00fccke zeigen kann. Die Karte habe ich mal wieder in meiner Lieblings Farbkombi Kirschbl\u00fcte, Schiefergrau und wei\u00df gestaltet.\u2026","rel":"","context":"In &quot;Team&quot;","block_context":{"text":"Team","link":"https:\/\/www.stempeltier.de\/blog\/category\/team\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2020\/04\/stampin-up-willkommen-im-team-welcome-koala-geschenk-stempeltier-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2020\/04\/stampin-up-willkommen-im-team-welcome-koala-geschenk-stempeltier-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2020\/04\/stampin-up-willkommen-im-team-welcome-koala-geschenk-stempeltier-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2020\/04\/stampin-up-willkommen-im-team-welcome-koala-geschenk-stempeltier-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2020\/04\/stampin-up-willkommen-im-team-welcome-koala-geschenk-stempeltier-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2020\/04\/stampin-up-willkommen-im-team-welcome-koala-geschenk-stempeltier-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":4959,"url":"https:\/\/www.stempeltier.de\/blog\/post-fuer-lea-gemeinsam-mehr-erreichen\/","url_meta":{"origin":3899,"position":3},"title":"Post f\u00fcr LEA &#8211; Gemeinsam mehr erreichen","author":"Danny","date":"31. M\u00e4rz 2017","format":false,"excerpt":"Heute m\u00f6chte ich eine wundervolle Idee mit euch teilen, in der Hoffnung die ein oder andere von Euch f\u00fchlt sich zur Nachahmung berufen. Eine Karte von Lea Vor ein paar Wochen habe ich von der 14-j\u00e4hrigen LEA eine selbstgebastelte Osterkarte bekommen. Einfach so. Wir kennen uns nicht, sie hat mich\u2026","rel":"","context":"In &quot;Allgemein&quot;","block_context":{"text":"Allgemein","link":"https:\/\/www.stempeltier.de\/blog\/category\/allgemein\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2017\/03\/osterkarte-lea.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2017\/03\/osterkarte-lea.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2017\/03\/osterkarte-lea.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2017\/03\/osterkarte-lea.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2158,"url":"https:\/\/www.stempeltier.de\/blog\/nachwuchs-herzlich-willkommen\/","url_meta":{"origin":3899,"position":4},"title":"Nachwuchs im Team &#038; auf Erden","author":"Danny","date":"7. Februar 2016","format":false,"excerpt":"Ich freue mich so sehr, dass ich wieder ist eine Karte f\u00fcr ein neues Mitglied in der Stempeltier-Familie werkeln und auf die Reise schicken darf. Frei nach dem Leitspruch von Stampin' Up!: Wir lieben was wir tun, zu teilen was wir lieben und somit anderen zu helfen durch eigene Kreativit\u00e4t\u2026","rel":"","context":"In &quot;Allgemein&quot;","block_context":{"text":"Allgemein","link":"https:\/\/www.stempeltier.de\/blog\/category\/allgemein\/"},"img":{"alt_text":"stampin up willkommen gorgeoug grunge team demo werden einsteigen","src":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/02\/stampin-up-willkommen-gorgeoug-grunge-team-demo-werden-einsteigen.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/02\/stampin-up-willkommen-gorgeoug-grunge-team-demo-werden-einsteigen.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/02\/stampin-up-willkommen-gorgeoug-grunge-team-demo-werden-einsteigen.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2016\/02\/stampin-up-willkommen-gorgeoug-grunge-team-demo-werden-einsteigen.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8370,"url":"https:\/\/www.stempeltier.de\/blog\/willkommen-im-team\/","url_meta":{"origin":3899,"position":5},"title":"Willkommen im Team","author":"Danny","date":"4. M\u00e4rz 2019","format":false,"excerpt":"Wir befinden uns im letzten Monat und somit auf der Zielgeraden der Sale-A-Bration 2019. Noch ist Zeit sich das tolle Starterset im Wert von 230 \u20ac f\u00fcr nur 129 \u20ac zu schnappen. Infos findest du HIER. Das dachte sich vor Kurzem auch die liebe Ellen, die sich nun \u00fcber ein\u2026","rel":"","context":"In &quot;Team&quot;","block_context":{"text":"Team","link":"https:\/\/www.stempeltier.de\/blog\/category\/team\/"},"img":{"alt_text":"stampin up willkommen im Team farbf\u00e4cher k\u00e4nguruh wild auf gr\u00fc\u00dfe geschenk stempeltier demo werden starterset","src":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2019\/03\/PicsArt_03-04-05.32.49.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2019\/03\/PicsArt_03-04-05.32.49.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2019\/03\/PicsArt_03-04-05.32.49.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2019\/03\/PicsArt_03-04-05.32.49.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2019\/03\/PicsArt_03-04-05.32.49.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.stempeltier.de\/blog\/wp-content\/uploads\/2019\/03\/PicsArt_03-04-05.32.49.png?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.stempeltier.de\/blog\/wp-json\/wp\/v2\/posts\/3899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stempeltier.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stempeltier.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stempeltier.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stempeltier.de\/blog\/wp-json\/wp\/v2\/comments?post=3899"}],"version-history":[{"count":11,"href":"https:\/\/www.stempeltier.de\/blog\/wp-json\/wp\/v2\/posts\/3899\/revisions"}],"predecessor-version":[{"id":3913,"href":"https:\/\/www.stempeltier.de\/blog\/wp-json\/wp\/v2\/posts\/3899\/revisions\/3913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stempeltier.de\/blog\/wp-json\/wp\/v2\/media\/3904"}],"wp:attachment":[{"href":"https:\/\/www.stempeltier.de\/blog\/wp-json\/wp\/v2\/media?parent=3899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stempeltier.de\/blog\/wp-json\/wp\/v2\/categories?post=3899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stempeltier.de\/blog\/wp-json\/wp\/v2\/tags?post=3899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}